{"id":736,"date":"2020-07-02T18:19:53","date_gmt":"2020-07-02T16:19:53","guid":{"rendered":"http:\/\/www.photosjcb.fr\/?p=736"},"modified":"2020-07-02T18:29:02","modified_gmt":"2020-07-02T16:29:02","slug":"tout-dans-la-douceur-et-la-sensualite","status":"publish","type":"post","link":"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/","title":{"rendered":"Tout dans la douceur et la sensualit\u00e9"},"content":{"rendered":"\n<p>Un shooting un peu particulier parce qu&rsquo;on l&rsquo;a voulu un peu plus sensuel qu&rsquo;\u00e0 l&rsquo;habituel tout en restant tr\u00e8s propre <\/p>\n\n\n\n<figure class=\"is-layout-flex wp-block-gallery-1 wp-block-gallery columns-4 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"640\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-1024x640.jpg\" alt=\"\" data-id=\"754\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim\/\" class=\"wp-image-754\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-1024x640.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-300x188.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-768x480.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-1536x960.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2048x1280.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-1140x713.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-684x1024.jpg\" alt=\"\" data-id=\"755\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-2\/\" class=\"wp-image-755\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-684x1024.jpg 684w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-200x300.jpg 200w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-768x1151.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-1025x1536.jpg 1025w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-1367x2048.jpg 1367w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-1140x1708.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-2-scaled.jpg 1709w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-684x1024.jpg\" alt=\"\" data-id=\"756\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-3\/\" class=\"wp-image-756\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-684x1024.jpg 684w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-200x300.jpg 200w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-768x1151.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-1025x1536.jpg 1025w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-1367x2048.jpg 1367w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-1140x1708.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-3-scaled.jpg 1709w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"732\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-1024x732.jpg\" alt=\"\" data-id=\"757\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-4\/\" class=\"wp-image-757\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-1024x732.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-300x214.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-768x549.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-1536x1097.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-2048x1463.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-4-1140x814.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-1024x1024.jpg\" alt=\"\" data-id=\"758\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-5\/\" class=\"wp-image-758\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-1024x1024.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-300x300.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-150x150.jpg 150w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-768x768.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-1536x1536.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-2048x2048.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-1140x1140.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-5-75x75.jpg 75w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"576\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-576x1024.jpg\" alt=\"\" data-id=\"759\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-6\/\" class=\"wp-image-759\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-576x1024.jpg 576w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-169x300.jpg 169w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-768x1365.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-864x1536.jpg 864w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-1152x2048.jpg 1152w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-1140x2026.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-6-scaled.jpg 1440w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"684\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-1024x684.jpg\" alt=\"\" data-id=\"760\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-7\/\" class=\"wp-image-760\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-1024x684.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-300x200.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-768x513.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-1536x1025.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-2048x1367.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-7-1140x761.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"819\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-819x1024.jpg\" alt=\"\" data-id=\"762\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-8\/\" class=\"wp-image-762\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-819x1024.jpg 819w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-240x300.jpg 240w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-768x960.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-1229x1536.jpg 1229w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-1638x2048.jpg 1638w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-1140x1425.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-8-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"684\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-1024x684.jpg\" alt=\"\" data-id=\"763\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-9\/\" class=\"wp-image-763\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-1024x684.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-300x200.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-768x513.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-1536x1025.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-2048x1367.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-9-1140x761.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"640\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-1024x640.jpg\" alt=\"\" data-id=\"764\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-10\/\" class=\"wp-image-764\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-1024x640.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-300x187.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-768x480.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-1536x960.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-2048x1280.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-10-1140x712.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-1024x1024.jpg\" alt=\"\" data-id=\"765\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-11\/\" class=\"wp-image-765\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-1024x1024.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-300x300.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-150x150.jpg 150w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-768x768.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-1536x1536.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-2048x2048.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-1140x1140.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-11-75x75.jpg 75w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-1024x1024.jpg\" alt=\"\" data-id=\"766\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-12\/\" class=\"wp-image-766\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-1024x1024.jpg 1024w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-300x300.jpg 300w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-150x150.jpg 150w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-768x768.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-1536x1536.jpg 1536w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-2048x2048.jpg 2048w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-1140x1140.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-12-75x75.jpg 75w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-684x1024.jpg\" alt=\"\" data-id=\"767\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-13\/\" class=\"wp-image-767\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-684x1024.jpg 684w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-200x300.jpg 200w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-768x1151.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-1025x1536.jpg 1025w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-1367x2048.jpg 1367w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-1140x1708.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-13-scaled.jpg 1709w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-684x1024.jpg\" alt=\"\" data-id=\"768\" data-full-url=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-scaled.jpg\" data-link=\"http:\/\/www.photosjcb.fr\/index.php\/2020\/07\/02\/tout-dans-la-douceur-et-la-sensualite\/kim-14\/\" class=\"wp-image-768\" srcset=\"http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-684x1024.jpg 684w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-200x300.jpg 200w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-768x1151.jpg 768w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-1025x1536.jpg 1025w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-1367x2048.jpg 1367w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-1140x1708.jpg 1140w, http:\/\/www.photosjcb.fr\/wp-content\/uploads\/2020\/07\/kim-14-scaled.jpg 1709w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un shooting un peu particulier parce qu&rsquo;on l&rsquo;a voulu un peu plus sensuel qu&rsquo;\u00e0 l&rsquo;habituel tout en restant tr\u00e8s propre<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/posts\/736"}],"collection":[{"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":2,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"predecessor-version":[{"id":769,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/posts\/736\/revisions\/769"}],"wp:attachment":[{"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.photosjcb.fr\/index.php\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}